{"id":15444,"date":"2023-10-11T11:30:05","date_gmt":"2023-10-11T09:30:05","guid":{"rendered":"https:\/\/egerhaziimre.hu\/?page_id=15444"},"modified":"2023-10-11T11:35:01","modified_gmt":"2023-10-11T09:35:01","slug":"latomas-felelem","status":"publish","type":"page","link":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/latomas-felelem\/","title":{"rendered":"L\u00e1tom\u00e1s I. F\u00e9lelem"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading source=&#8221;post_title&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;mb60 mb30-md&#8221;][vc_empty_space][vc_single_image image=&#8221;4041&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221; style=&#8221;xtd-shadow&#8211;large-normal&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; link=&#8221;https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/174.jpg&#8221;][vc_empty_space][vc_column_text]\n<p style=\"text-align: center;\">olaj, farost, 60&#215;80 cm<br \/>\n1989<\/p>\n<p><!--more-->[\/vc_column_text][vc_separator][vc_btn title=&#8221;Vissza az \u00c9letm\u0171 oldalra&#8221; shape=&#8221;square&#8221; color=&#8221;warning&#8221; align=&#8221;center&#8221; i_icon_fontawesome=&#8221;fas fa-angle-double-left&#8221; add_icon=&#8221;true&#8221; el_class=&#8221;mb60 mb30-md&#8221; link=&#8221;url:http%3A%2F%2Fegerhaziimre.magex.hu%2Findex.php%2Feletmu%2F|title:%C3%89letm%C5%B1||&#8221;][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_custom_heading source=&#8221;post_title&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;mb60 mb30-md&#8221;][vc_empty_space][vc_single_image image=&#8221;4041&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221; style=&#8221;xtd-shadow&#8211;large-normal&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; link=&#8221;https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/174.jpg&#8221;][vc_empty_space][vc_column_text] olaj, farost, 60&#215;80 cm 1989<\/p>\n","protected":false},"author":5,"featured_media":4041,"parent":3496,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[128],"tags":[80,152],"class_list":["post-15444","page","type-page","status-publish","has-post-thumbnail","hentry","category-festmenyek","tag-80","tag-olajfestmeny"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L\u00e1tom\u00e1s I. F\u00e9lelem - \u00c9gerh\u00e1zi Imre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/latomas-felelem\/\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9gerh\u00e1zi Imre\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_custom_heading source=&#8221;post_title&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;mb60 mb30-md&#8221;][vc_empty_space][vc_single_image image=&#8221;4041&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221; style=&#8221;xtd-shadow&#8211;large-normal&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; link=&#8221;https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/174.jpg&#8221;][vc_empty_space][vc_column_text] olaj, farost, 60&#215;80 cm 1989\" \/>\n<meta property=\"og:url\" content=\"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/latomas-felelem\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9gerh\u00e1zi Imre\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-11T09:35:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/174.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1498\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00c9gerh\u00e1zi Imre\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/174.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Becs\u00fclt olvas\u00e1si id\u0151\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 perc\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/egerhaziimre.hu\\\/index.php\\\/eletmu\\\/latomas-felelem\\\/\",\"url\":\"https:\\\/\\\/egerhaziimre.hu\\\/index.php\\\/eletmu\\\/latomas-felelem\\\/\",\"name\":\"L\u00e1tom\u00e1s I. F\u00e9lelem - \u00c9gerh\u00e1zi Imre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/egerhaziimre.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/egerhaziimre.hu\\\/index.php\\\/eletmu\\\/latomas-felelem\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/egerhaziimre.hu\\\/index.php\\\/eletmu\\\/latomas-felelem\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/egerhaziimre.hu\\\/wp-content\\\/uploads\\\/kepek\\\/174.jpg\",\"datePublished\":\"2023-10-11T09:30:05+00:00\",\"dateModified\":\"2023-10-11T09:35:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/egerhaziimre.hu\\\/index.php\\\/eletmu\\\/latomas-felelem\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/egerhaziimre.hu\\\/index.php\\\/eletmu\\\/latomas-felelem\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/egerhaziimre.hu\\\/index.php\\\/eletmu\\\/latomas-felelem\\\/#primaryimage\",\"url\":\"https:\\\/\\\/egerhaziimre.hu\\\/wp-content\\\/uploads\\\/kepek\\\/174.jpg\",\"contentUrl\":\"https:\\\/\\\/egerhaziimre.hu\\\/wp-content\\\/uploads\\\/kepek\\\/174.jpg\",\"width\":2000,\"height\":1498,\"caption\":\"olaj, farost 60x80 1989\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/egerhaziimre.hu\\\/index.php\\\/eletmu\\\/latomas-felelem\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/egerhaziimre.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Life work\",\"item\":\"https:\\\/\\\/egerhaziimre.hu\\\/index.php\\\/eletmu\\\/?lang=en\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"L\u00e1tom\u00e1s I. F\u00e9lelem\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/egerhaziimre.hu\\\/#website\",\"url\":\"https:\\\/\\\/egerhaziimre.hu\\\/\",\"name\":\"\u00c9gerh\u00e1zi Imre\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/egerhaziimre.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L\u00e1tom\u00e1s I. F\u00e9lelem - \u00c9gerh\u00e1zi Imre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/latomas-felelem\/","og_locale":"hu_HU","og_type":"article","og_title":"\u00c9gerh\u00e1zi Imre","og_description":"[vc_row][vc_column][vc_custom_heading source=&#8221;post_title&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;mb60 mb30-md&#8221;][vc_empty_space][vc_single_image image=&#8221;4041&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221; style=&#8221;xtd-shadow&#8211;large-normal&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; link=&#8221;https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/174.jpg&#8221;][vc_empty_space][vc_column_text] olaj, farost, 60&#215;80 cm 1989","og_url":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/latomas-felelem\/","og_site_name":"\u00c9gerh\u00e1zi Imre","article_modified_time":"2023-10-11T09:35:01+00:00","og_image":[{"width":2000,"height":1498,"url":"https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/174.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"\u00c9gerh\u00e1zi Imre","twitter_image":"https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/174.jpg","twitter_misc":{"Becs\u00fclt olvas\u00e1si id\u0151":"1 perc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/latomas-felelem\/","url":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/latomas-felelem\/","name":"L\u00e1tom\u00e1s I. F\u00e9lelem - \u00c9gerh\u00e1zi Imre","isPartOf":{"@id":"https:\/\/egerhaziimre.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/latomas-felelem\/#primaryimage"},"image":{"@id":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/latomas-felelem\/#primaryimage"},"thumbnailUrl":"https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/174.jpg","datePublished":"2023-10-11T09:30:05+00:00","dateModified":"2023-10-11T09:35:01+00:00","breadcrumb":{"@id":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/latomas-felelem\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/egerhaziimre.hu\/index.php\/eletmu\/latomas-felelem\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/latomas-felelem\/#primaryimage","url":"https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/174.jpg","contentUrl":"https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/174.jpg","width":2000,"height":1498,"caption":"olaj, farost 60x80 1989"},{"@type":"BreadcrumbList","@id":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/latomas-felelem\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/egerhaziimre.hu\/"},{"@type":"ListItem","position":2,"name":"Life work","item":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/?lang=en"},{"@type":"ListItem","position":3,"name":"L\u00e1tom\u00e1s I. F\u00e9lelem"}]},{"@type":"WebSite","@id":"https:\/\/egerhaziimre.hu\/#website","url":"https:\/\/egerhaziimre.hu\/","name":"\u00c9gerh\u00e1zi Imre","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/egerhaziimre.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/pages\/15444","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/comments?post=15444"}],"version-history":[{"count":1,"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/pages\/15444\/revisions"}],"predecessor-version":[{"id":15445,"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/pages\/15444\/revisions\/15445"}],"up":[{"embeddable":true,"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/pages\/3496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/media\/4041"}],"wp:attachment":[{"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/media?parent=15444"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/categories?post=15444"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/tags?post=15444"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}