{"id":18075,"date":"2024-07-23T13:58:59","date_gmt":"2024-07-23T11:58:59","guid":{"rendered":"https:\/\/egerhaziimre.hu\/?page_id=18075"},"modified":"2024-07-23T14:39:51","modified_gmt":"2024-07-23T12:39:51","slug":"teli-erdelyi-falu2","status":"publish","type":"page","link":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/teli-erdelyi-falu2\/","title":{"rendered":"T\u00e9li erd\u00e9lyi falu"},"content":{"rendered":"<div class=\"wpb-content-wrapper\">[vc_row][vc_column][vc_custom_heading source=&#8221;post_title&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;mb60 mb30-md&#8221;][vc_empty_space][vc_single_image image=&#8221;13800&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221; style=&#8221;xtd-shadow&#8211;large-normal&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; link=&#8221;https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/2661.jpg&#8221;][vc_empty_space][vc_column_text]\n<p style=\"text-align: center;\">olaj, farost, 80&#215;100 cm<br \/>\n1989<\/p>\n<p><!--more-->[\/vc_column_text][vc_separator][vc_btn title=&#8221;Vissza az \u00c9letm\u0171 oldalra&#8221; shape=&#8221;square&#8221; color=&#8221;warning&#8221; align=&#8221;center&#8221; i_icon_fontawesome=&#8221;fas fa-angle-double-left&#8221; add_icon=&#8221;true&#8221; el_class=&#8221;mb60 mb30-md&#8221; link=&#8221;url:http%3A%2F%2Fegerhaziimre.magex.hu%2Findex.php%2Feletmu%2F|title:%C3%89letm%C5%B1||&#8221;][\/vc_column][\/vc_row]\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_custom_heading source=&#8221;post_title&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;mb60 mb30-md&#8221;][vc_empty_space][vc_single_image image=&#8221;13800&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221; style=&#8221;xtd-shadow&#8211;large-normal&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; link=&#8221;https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/2661.jpg&#8221;][vc_empty_space][vc_column_text] olaj, farost, 80&#215;100 cm 1989<\/p>\n","protected":false},"author":5,"featured_media":13800,"parent":3496,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"categories":[128],"tags":[80,152],"class_list":["post-18075","page","type-page","status-publish","has-post-thumbnail","hentry","category-festmenyek","tag-80","tag-olajfestmeny"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>T\u00e9li erd\u00e9lyi falu - \u00c9gerh\u00e1zi Imre<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/teli-erdelyi-falu2\/\" \/>\n<meta property=\"og:locale\" content=\"hu_HU\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00c9gerh\u00e1zi Imre\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_custom_heading source=&#8221;post_title&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;mb60 mb30-md&#8221;][vc_empty_space][vc_single_image image=&#8221;13800&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221; style=&#8221;xtd-shadow&#8211;large-normal&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; link=&#8221;https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/2661.jpg&#8221;][vc_empty_space][vc_column_text] olaj, farost, 80&#215;100 cm 1989\" \/>\n<meta property=\"og:url\" content=\"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/teli-erdelyi-falu2\/\" \/>\n<meta property=\"og:site_name\" content=\"\u00c9gerh\u00e1zi Imre\" \/>\n<meta property=\"article:modified_time\" content=\"2024-07-23T12:39:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/2661-1024x889.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"889\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00c9gerh\u00e1zi Imre\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/2661.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Becs\u00fclt olvas\u00e1si id\u0151\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 perc\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/egerhaziimre.hu\\\/index.php\\\/eletmu\\\/teli-erdelyi-falu2\\\/\",\"url\":\"https:\\\/\\\/egerhaziimre.hu\\\/index.php\\\/eletmu\\\/teli-erdelyi-falu2\\\/\",\"name\":\"T\u00e9li erd\u00e9lyi falu - \u00c9gerh\u00e1zi Imre\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/egerhaziimre.hu\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/egerhaziimre.hu\\\/index.php\\\/eletmu\\\/teli-erdelyi-falu2\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/egerhaziimre.hu\\\/index.php\\\/eletmu\\\/teli-erdelyi-falu2\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/egerhaziimre.hu\\\/wp-content\\\/uploads\\\/kepek\\\/2661.jpg\",\"datePublished\":\"2024-07-23T11:58:59+00:00\",\"dateModified\":\"2024-07-23T12:39:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/egerhaziimre.hu\\\/index.php\\\/eletmu\\\/teli-erdelyi-falu2\\\/#breadcrumb\"},\"inLanguage\":\"hu\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/egerhaziimre.hu\\\/index.php\\\/eletmu\\\/teli-erdelyi-falu2\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"hu\",\"@id\":\"https:\\\/\\\/egerhaziimre.hu\\\/index.php\\\/eletmu\\\/teli-erdelyi-falu2\\\/#primaryimage\",\"url\":\"https:\\\/\\\/egerhaziimre.hu\\\/wp-content\\\/uploads\\\/kepek\\\/2661.jpg\",\"contentUrl\":\"https:\\\/\\\/egerhaziimre.hu\\\/wp-content\\\/uploads\\\/kepek\\\/2661.jpg\",\"width\":2000,\"height\":1736,\"caption\":\"olaj, farost 80x100\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/egerhaziimre.hu\\\/index.php\\\/eletmu\\\/teli-erdelyi-falu2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/egerhaziimre.hu\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Life work\",\"item\":\"https:\\\/\\\/egerhaziimre.hu\\\/index.php\\\/eletmu\\\/?lang=en\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"T\u00e9li erd\u00e9lyi falu\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/egerhaziimre.hu\\\/#website\",\"url\":\"https:\\\/\\\/egerhaziimre.hu\\\/\",\"name\":\"\u00c9gerh\u00e1zi Imre\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/egerhaziimre.hu\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"hu\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"T\u00e9li erd\u00e9lyi falu - \u00c9gerh\u00e1zi Imre","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/teli-erdelyi-falu2\/","og_locale":"hu_HU","og_type":"article","og_title":"\u00c9gerh\u00e1zi Imre","og_description":"[vc_row][vc_column][vc_custom_heading source=&#8221;post_title&#8221; font_container=&#8221;tag:h2|text_align:center&#8221; use_theme_fonts=&#8221;yes&#8221; el_class=&#8221;mb60 mb30-md&#8221;][vc_empty_space][vc_single_image image=&#8221;13800&#8243; img_size=&#8221;large&#8221; alignment=&#8221;center&#8221; style=&#8221;xtd-shadow&#8211;large-normal&#8221; onclick=&#8221;custom_link&#8221; img_link_target=&#8221;_blank&#8221; link=&#8221;https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/2661.jpg&#8221;][vc_empty_space][vc_column_text] olaj, farost, 80&#215;100 cm 1989","og_url":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/teli-erdelyi-falu2\/","og_site_name":"\u00c9gerh\u00e1zi Imre","article_modified_time":"2024-07-23T12:39:51+00:00","og_image":[{"width":1024,"height":889,"url":"https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/2661-1024x889.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"\u00c9gerh\u00e1zi Imre","twitter_image":"https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/2661.jpg","twitter_misc":{"Becs\u00fclt olvas\u00e1si id\u0151":"1 perc"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/teli-erdelyi-falu2\/","url":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/teli-erdelyi-falu2\/","name":"T\u00e9li erd\u00e9lyi falu - \u00c9gerh\u00e1zi Imre","isPartOf":{"@id":"https:\/\/egerhaziimre.hu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/teli-erdelyi-falu2\/#primaryimage"},"image":{"@id":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/teli-erdelyi-falu2\/#primaryimage"},"thumbnailUrl":"https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/2661.jpg","datePublished":"2024-07-23T11:58:59+00:00","dateModified":"2024-07-23T12:39:51+00:00","breadcrumb":{"@id":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/teli-erdelyi-falu2\/#breadcrumb"},"inLanguage":"hu","potentialAction":[{"@type":"ReadAction","target":["https:\/\/egerhaziimre.hu\/index.php\/eletmu\/teli-erdelyi-falu2\/"]}]},{"@type":"ImageObject","inLanguage":"hu","@id":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/teli-erdelyi-falu2\/#primaryimage","url":"https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/2661.jpg","contentUrl":"https:\/\/egerhaziimre.hu\/wp-content\/uploads\/kepek\/2661.jpg","width":2000,"height":1736,"caption":"olaj, farost 80x100"},{"@type":"BreadcrumbList","@id":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/teli-erdelyi-falu2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/egerhaziimre.hu\/"},{"@type":"ListItem","position":2,"name":"Life work","item":"https:\/\/egerhaziimre.hu\/index.php\/eletmu\/?lang=en"},{"@type":"ListItem","position":3,"name":"T\u00e9li erd\u00e9lyi falu"}]},{"@type":"WebSite","@id":"https:\/\/egerhaziimre.hu\/#website","url":"https:\/\/egerhaziimre.hu\/","name":"\u00c9gerh\u00e1zi Imre","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/egerhaziimre.hu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"hu"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/pages\/18075","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/comments?post=18075"}],"version-history":[{"count":2,"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/pages\/18075\/revisions"}],"predecessor-version":[{"id":18082,"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/pages\/18075\/revisions\/18082"}],"up":[{"embeddable":true,"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/pages\/3496"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/media\/13800"}],"wp:attachment":[{"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/media?parent=18075"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/categories?post=18075"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/egerhaziimre.hu\/index.php\/wp-json\/wp\/v2\/tags?post=18075"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}